{"id":6196,"date":"2026-05-10T09:35:00","date_gmt":"2026-05-10T09:35:00","guid":{"rendered":"https:\/\/jozotg.com\/?post_type=yrwp&#038;p=6196"},"modified":"2026-05-09T09:41:39","modified_gmt":"2026-05-09T09:41:39","slug":"3-axle-50ton-dump-semi-trailer-2","status":"publish","type":"yrwp","link":"https:\/\/jozotg.com\/vi\/products\/3-axle-50ton-dump-semi-trailer-2\/","title":{"rendered":"3 Axle 60 Ton Hydraulic Tipper Dump Semi Trailer"},"content":{"rendered":"<style>.kt-tabs-id6196_0ba1ab-57 > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:1px solid rgba(21,20,34,0.15);border-right:0px solid #0a6689;border-bottom:0px solid #0a6689;border-left:0px solid #0a6689;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:0px;padding-bottom:0px;padding-left:0px;background:var(u002du002dglobal-palette9, #ffffff);}.wp-block-kadence-tabs .kt-tabs-id6196_0ba1ab-57 > .kt-tabs-title-list li{margin-top:0px;margin-right:8px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-tabs .kt-tabs-id6196_0ba1ab-57 > .kt-tabs-title-list li:last-child{margin-right:0px;}.wp-block-kadence-tabs .kt-tabs-id6196_0ba1ab-57 > .kt-tabs-title-list li .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id6196_0ba1ab-57 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{font-size:20px;line-height:1.4em;font-family:-apple-system,BlinkMacSystemFont,u0022Segoe UIu0022,Roboto,Oxygen-Sans,Ubuntu,Cantarell,u0022Helvetica Neueu0022,sans-serif, u0022Apple Color Emojiu0022, u0022Segoe UI Emojiu0022, u0022Segoe UI Symbolu0022;font-weight:600;font-style:normal;text-transform:capitalize;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:8px;padding-right:20px;padding-bottom:8px;padding-left:20px;border-color:var(u002du002dglobal-palette7, #eeeeee);color:rgba(255,255,255,0.85);background:rgba(21,20,34,0.35);}.wp-block-kadence-tabs .kt-tabs-id6196_0ba1ab-57 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{margin-top:0px;margin-right:8px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-tabs .kt-tabs-id6196_0ba1ab-57 > .kt-tabs-title-list li .kt-tab-title:hover, .wp-block-kadence-tabs .kt-tabs-id6196_0ba1ab-57 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title:hover{border-color:var(u002du002dglobal-palette7, #eeeeee);color:#ffffff;background:#151422;}.wp-block-kadence-tabs .kt-tabs-id6196_0ba1ab-57 > .kt-tabs-title-list li.kt-tab-title-active .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id6196_0ba1ab-57 > .kt-tabs-content-wrap > .kt-tabs-accordion-title.kt-tab-title-active .kt-tab-title{border-color:var(u002du002dglobal-palette7, #eeeeee);color:#ffffff;background:#151422;}@media all and (max-width: 1024px){.kt-tabs-id6196_0ba1ab-57 > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:1px solid rgba(21,20,34,0.15);border-right:0px solid #0a6689;border-bottom:0px solid #0a6689;border-left:0px solid #0a6689;}}@media all and (max-width: 1024px){.wp-block-kadence-tabs .kt-tabs-id6196_0ba1ab-57 > .kt-tabs-title-list li .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id6196_0ba1ab-57 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{font-size:16px;}}@media all and (max-width: 767px){.kt-tabs-id6196_0ba1ab-57 > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:0px solid rgba(21,20,34,0.15);border-right:0px solid #0a6689;border-bottom:0px solid #0a6689;border-left:0px solid #0a6689;padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.wp-block-kadence-tabs .kt-tabs-id6196_0ba1ab-57 > .kt-tabs-title-list li{margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);}.wp-block-kadence-tabs .kt-tabs-id6196_0ba1ab-57 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{margin-bottom:var(--global-kb-spacing-xxs, 0.5rem);}.wp-block-kadence-tabs .kt-tabs-id6196_0ba1ab-57 > .kt-tabs-title-list li .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id6196_0ba1ab-57 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{font-size:px;}}<\/style>\n<div class=\"wp-block-kadence-tabs alignnone\"><div class=\"kt-tabs-wrap kt-tabs-id6196_0ba1ab-57 kt-tabs-has-3-tabs kt-active-tab-1 kt-tabs-layout-tabs kt-tabs-tablet-layout-inherit kt-tabs-mobile-layout-accordion kt-tab-alignment-left kt-create-accordion\" data-no-allow-multiple-open=\"true\"><ul class=\"kt-tabs-title-list\"><li id=\"tab-productdetails\" class=\"kt-title-item kt-title-item-1 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-active\"><a href=\"#tab-productdetails\" data-tab=\"1\" class=\"kt-tab-title kt-tab-title-1\"><span class=\"kt-title-text\">Product Details<\/span><\/a><\/li><li id=\"tab-parameter\" class=\"kt-title-item kt-title-item-2 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-parameter\" data-tab=\"2\" class=\"kt-tab-title kt-tab-title-2\"><span class=\"kt-title-text\">Parameter<\/span><\/a><\/li><li id=\"tab-faqs\" class=\"kt-title-item kt-title-item-3 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-faqs\" data-tab=\"3\" class=\"kt-tab-title kt-tab-title-3\"><span class=\"kt-title-text\">FAQs<\/span><\/a><\/li><\/ul><div class=\"kt-tabs-content-wrap\">\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-1 kt-inner-tab6196_dc772c-da\"><div class=\"kt-tab-inner-content-inner\">\n<p>Chinese Factory Customized New 2 3 4 Axles 30 40 50 60 Ton Hydraulic Tipper Dump Semi Trailer<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img alt=\"3 Axle 60 Ton Hydraulic Tipper Dump Semi Trailer-semi trailer-Shandong Jiuzhou Automobile Manufacturing Co., Ltd.\" title=\"3 Axle 60 Ton Hydraulic Tipper Dump Semi Trailer-semi trailer-Shandong Jiuzhou Automobile Manufacturing Co., Ltd.\" fetchpriority=\"high\" decoding=\"async\" width=\"750\" height=\"424\" src=\"https:\/\/jozotg.com\/wp-content\/uploads\/2026\/05\/4-1-2.webp\" class=\"wp-image-6204\" style=\"width:748px;height:auto\" srcset=\"https:\/\/jozotg.com\/wp-content\/uploads\/2026\/05\/4-1-2.webp 750w, https:\/\/jozotg.com\/wp-content\/uploads\/2026\/05\/4-1-2-18x10.webp 18w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-amber-color\"> 3 Axle Dump Trailer<\/mark> 10000USD<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img alt=\"3 Axle 60 Ton Hydraulic Tipper Dump Semi Trailer-semi trailer-Shandong Jiuzhou Automobile Manufacturing Co., Ltd.\" title=\"3 Axle 60 Ton Hydraulic Tipper Dump Semi Trailer-semi trailer-Shandong Jiuzhou Automobile Manufacturing Co., Ltd.\" decoding=\"async\" width=\"750\" height=\"552\" src=\"https:\/\/jozotg.com\/wp-content\/uploads\/2026\/05\/4-2-2.webp\" class=\"wp-image-6205\" srcset=\"https:\/\/jozotg.com\/wp-content\/uploads\/2026\/05\/4-2-2.webp 750w, https:\/\/jozotg.com\/wp-content\/uploads\/2026\/05\/4-2-2-16x12.webp 16w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" style=\"border-bottom-width:1px;padding-top:10px;padding-right:10px;padding-bottom:10px\"><strong>Core Components<\/strong><\/h3>\n\n\n\n<p>The high &#8211; quality hub &#8211; centric wheels with deep &#8211; etched brand markings ensure precise fitment and reliable performance. Paired with durable tires, they offer excellent stability and load &#8211; bearing capacity, enhancing the safety and efficiency of long &#8211; haul transportation.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img alt=\"3 Axle 60 Ton Hydraulic Tipper Dump Semi Trailer-semi trailer-Shandong Jiuzhou Automobile Manufacturing Co., Ltd.\" title=\"3 Axle 60 Ton Hydraulic Tipper Dump Semi Trailer-semi trailer-Shandong Jiuzhou Automobile Manufacturing Co., Ltd.\" decoding=\"async\" width=\"750\" height=\"508\" src=\"https:\/\/jozotg.com\/wp-content\/uploads\/2026\/02\/5-1-7.webp\" class=\"wp-image-5186\"\/><\/figure>\n\n\n\n<p>The heavy &#8211; duty support leg with clear instruction labels and a robust structure provides stable parking support and effortless height adjustment. Its durable construction ensures long &#8211; term reliability, minimizing downtime during loading and unloading operations.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img alt=\"3 Axle 60 Ton Hydraulic Tipper Dump Semi Trailer-semi trailer-Shandong Jiuzhou Automobile Manufacturing Co., Ltd.\" title=\"3 Axle 60 Ton Hydraulic Tipper Dump Semi Trailer-semi trailer-Shandong Jiuzhou Automobile Manufacturing Co., Ltd.\" loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"634\" src=\"https:\/\/jozotg.com\/wp-content\/uploads\/2026\/02\/5-3-3.webp\" class=\"wp-image-5187\" style=\"width:740px;height:auto\"\/><\/figure>\n\n\n\n<p>The advanced suspension system with high &#8211; strength leaf springs and precision &#8211; engineered components effectively absorbs road shocks, ensuring a smooth ride for cargo and reducing wear on both the trailer and the transported goods, thus optimizing overall transport performance.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img alt=\"3 Axle 60 Ton Hydraulic Tipper Dump Semi Trailer-semi trailer-Shandong Jiuzhou Automobile Manufacturing Co., Ltd.\" title=\"3 Axle 60 Ton Hydraulic Tipper Dump Semi Trailer-semi trailer-Shandong Jiuzhou Automobile Manufacturing Co., Ltd.\" loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"676\" src=\"https:\/\/jozotg.com\/wp-content\/uploads\/2026\/02\/5-4.webp\" class=\"wp-image-5188\"\/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" style=\"border-bottom-width:1px;padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:0px\"><strong>Design Drawings<\/strong><\/h3>\n\n\n\n<figure class=\"wp-block-image size-full\"><img alt=\"3 Axle 60 Ton Hydraulic Tipper Dump Semi Trailer-semi trailer-Shandong Jiuzhou Automobile Manufacturing Co., Ltd.\" title=\"3 Axle 60 Ton Hydraulic Tipper Dump Semi Trailer-semi trailer-Shandong Jiuzhou Automobile Manufacturing Co., Ltd.\" loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/jozotg.com\/wp-content\/uploads\/2025\/08\/rear-dump-tuzhi.webp\" class=\"wp-image-2420\" srcset=\"https:\/\/jozotg.com\/wp-content\/uploads\/2025\/08\/rear-dump-tuzhi.webp 750w, https:\/\/jozotg.com\/wp-content\/uploads\/2025\/08\/rear-dump-tuzhi-18x12.webp 18w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/figure>\n\n\n\n<p><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-2 kt-inner-tab6196_763cf7-3d\"><div class=\"kt-tab-inner-content-inner\">\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td>Product Name<\/td><td><a href=\"https:\/\/www.jozotgvehicle.com\/rear-dump-trailer\/3-axle-rear-dump.html\" target=\"_blank\" rel=\"noopener\"> Dump Semi Trailer<\/a><\/td><\/tr><tr><td>Outside Dimension(L*W*H)(mm)<\/td><td>13000x2550x2700mm (customizable)<\/td><\/tr><tr><td>Max Loading Capacity (kg)<\/td><td>30000-100000&nbsp;\uff08customizable)<\/td><\/tr><tr><td>Tare Weight<\/td><td>50-80 Tons<\/td><\/tr><tr><td>Main Beam<\/td><td>Q345B manganese plates, automatic submerged arc welded<\/td><\/tr><tr><td>&nbsp;<\/td><td>Upper:14mm, Lower:16mm, Mid web:8mm<\/td><\/tr><tr><td>&nbsp;<\/td><td>The height of beam:500mm,<\/td><\/tr><tr><td>Floor<\/td><td>Steel sheet 4mm thickness or diamond plate<\/td><\/tr><tr><td>Tyre Specifications<\/td><td>11.00R20\/12R222.5 Linglong\/Triangle\/DoublCoin<\/td><\/tr><tr><td>Rim<\/td><td>9.0-22.5 rims<\/td><\/tr><tr><td><a href=\"https:\/\/www.jozotgvehicle.com\/axle\/\" target=\"_blank\" rel=\"noopener\">Axle<\/a><\/td><td>13 T\/16TFuwa \/ BPW\/JOZOTG\/Other<\/td><\/tr><tr><td>Leaf-spring<\/td><td>90(W)mm*13(Thickness)mm*10 Layer or100mm*12mm*12<\/td><\/tr><tr><td>Suspension<\/td><td>Mechanical\/ Air suspension<\/td><\/tr><tr><td>Brake Air Chamber<\/td><td>WABCO RE 6 relay valve<\/td><\/tr><tr><td>King Pin<\/td><td>#50(2&#8243;)\/#90(3.5&#8243;), JOST\/Other Brand<\/td><\/tr><tr><td>Landing Gear<\/td><td>28000 kg,JOST<\/td><\/tr><tr><td>Spare Wheel Carrier<\/td><td>One set of spare wheel carrier<\/td><\/tr><tr><td>Accessory<\/td><td>One tooling box with a set of standard trailer tool<\/td><\/tr><tr><td>Electrical System<\/td><td>24V, 7core socket, lights according to European standards.<\/td><\/tr><tr><td>Tool Box<\/td><td>Steel\/aluminum One piece,1m*0.5m*0.5m(Size can be choose freely)<\/td><\/tr><\/tbody><\/table><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-3 kt-inner-tab6196_405e75-00\"><div class=\"kt-tab-inner-content-inner\"><style>.kt-accordion-id6196_74c140-74 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:5px;}.kt-accordion-id6196_74c140-74 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:0px;padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:0px;}.kt-accordion-id6196_74c140-74 .wp-block-kadence-pane .kt-accordion-header-wrap .kt-blocks-accordion-header{border-top:1px solid rgba(0,0,0,0.2);border-right:1px solid rgba(0,0,0,0.2);border-bottom:1px solid rgba(0,0,0,0.2);border-left:1px solid rgba(0,0,0,0.2);border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(0,0,0,0);color:#555555;padding-top:12px;padding-right:12px;padding-bottom:12px;padding-left:12px;}.kt-accordion-id6196_74c140-74:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id6196_74c140-74:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-icon-trigger:before{background:#555555;}.kt-accordion-id6196_74c140-74:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#555555;}.kt-accordion-id6196_74c140-74:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id6196_74c140-74:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:rgba(0,0,0,0);}.kt-accordion-id6196_74c140-74 .kt-accordion-header-wrap .kt-blocks-accordion-header:hover, body:not(.hide-focus-outline) .kt-accordion-id6196_74c140-74 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible{color:#444444;background:#eeeeee;border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id6196_74c140-74:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id6196_74c140-74:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id6196_74c140-74:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id6196_74c140-74:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id6196_74c140-74:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id6196_74c140-74:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id6196_74c140-74:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id6196_74c140-74:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id6196_74c140-74:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id6196_74c140-74:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#eeeeee;}.kt-accordion-id6196_74c140-74 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible, .kt-accordion-id6196_74c140-74 .kt-accordion-header-wrap .kt-blocks-accordion-header.kt-accordion-panel-active{color:#000000;border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}.kt-accordion-id6196_74c140-74:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id6196_74c140-74:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#000000;}.kt-accordion-id6196_74c140-74:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#000000;}@media all and (max-width: 1024px){.kt-accordion-id6196_74c140-74 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id6196_74c140-74 .wp-block-kadence-pane .kt-accordion-header-wrap .kt-blocks-accordion-header{border-top:1px solid rgba(0,0,0,0.2);border-right:1px solid rgba(0,0,0,0.2);border-bottom:1px solid rgba(0,0,0,0.2);border-left:1px solid rgba(0,0,0,0.2);}}@media all and (max-width: 1024px){.kt-accordion-id6196_74c140-74 .kt-accordion-header-wrap .kt-blocks-accordion-header:hover, body:not(.hide-focus-outline) .kt-accordion-id6196_74c140-74 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id6196_74c140-74 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible, .kt-accordion-id6196_74c140-74 .kt-accordion-header-wrap .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id6196_74c140-74 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id6196_74c140-74 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:5px;}.kt-accordion-id6196_74c140-74 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id6196_74c140-74 .wp-block-kadence-pane .kt-accordion-header-wrap .kt-blocks-accordion-header{border-top:1px solid rgba(0,0,0,0.2);border-right:1px solid rgba(0,0,0,0.2);border-bottom:1px solid rgba(0,0,0,0.2);border-left:1px solid rgba(0,0,0,0.2);}.kt-accordion-id6196_74c140-74 .kt-accordion-header-wrap .kt-blocks-accordion-header:hover, body:not(.hide-focus-outline) .kt-accordion-id6196_74c140-74 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#eeeeee;border-left-style:solid;}.kt-accordion-id6196_74c140-74 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible, .kt-accordion-id6196_74c140-74 .kt-accordion-header-wrap .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#444444;border-top-style:solid;border-right-color:#444444;border-right-style:solid;border-bottom-color:#444444;border-bottom-style:solid;border-left-color:#444444;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id6196_74c140-74 kt-accordion-has-5-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-arrow kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"0\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane6196_75cca0-17\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\"><strong>What types of cargo are rear-discharge semi-trailers suitable for?<\/strong><\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>Rear-discharge semi-trailers are ideal for transporting bulk materials such as sand, gravel, coal, and grain. Their rear-discharge design allows for quick unloading, significantly improving work efficiency, making them a reliable assistant for construction sites and logistics transportation!<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-2 kt-pane6196_00512e-cf\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">How efficient is the unloading process of rear-discharge semi-trailers?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>Our rear-discharge semi-trailers are equipped with a hydraulic rear-discharge system, which ensures fast and easy unloading. The entire unloading process can be completed in just a few minutes, saving both time and labor costs.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane6196_7658cd-00\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">What is the load capacity of rear-discharge semi-trailers?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>Rear-discharge semi-trailers are made of high-strength steel and have a maximum load capacity of 80 tons, making them capable of handling heavy bulk materials with ease and ensuring safe and reliable transportation every time.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-4 kt-pane6196_e19920-c3\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Are rear-discharge semi-trailers suitable for use in harsh environments?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>Absolutely! Our rear-discharge semi-trailers feature anti-rust treatment and reinforced design, enabling them to operate stably in harsh environments over the long term. Whether on construction sites or in mining areas, they deliver excellent performance.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-5 kt-pane6196_8617f0-04\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">How is after-sales service handled if issues arise with rear-discharge semi-trailers?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>We offer a lifetime warranty on the main beam and a lifetime warranty on the hydraulic system. Our after-sales team is available 24\/7 to resolve any issues promptly, ensuring your transportation operations run smoothly and worry-free!<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":6203,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"allproducts":[38],"all-tags":[],"class_list":["post-6196","yrwp","type-yrwp","status-publish","has-post-thumbnail","hentry","allproducts-rear-dump-trailer"],"_links":{"self":[{"href":"https:\/\/jozotg.com\/vi\/wp-json\/wp\/v2\/yrwp\/6196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jozotg.com\/vi\/wp-json\/wp\/v2\/yrwp"}],"about":[{"href":"https:\/\/jozotg.com\/vi\/wp-json\/wp\/v2\/types\/yrwp"}],"author":[{"embeddable":true,"href":"https:\/\/jozotg.com\/vi\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/jozotg.com\/vi\/wp-json\/wp\/v2\/comments?post=6196"}],"version-history":[{"count":3,"href":"https:\/\/jozotg.com\/vi\/wp-json\/wp\/v2\/yrwp\/6196\/revisions"}],"predecessor-version":[{"id":6207,"href":"https:\/\/jozotg.com\/vi\/wp-json\/wp\/v2\/yrwp\/6196\/revisions\/6207"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jozotg.com\/vi\/wp-json\/wp\/v2\/media\/6203"}],"wp:attachment":[{"href":"https:\/\/jozotg.com\/vi\/wp-json\/wp\/v2\/media?parent=6196"}],"wp:term":[{"taxonomy":"allproducts","embeddable":true,"href":"https:\/\/jozotg.com\/vi\/wp-json\/wp\/v2\/allproducts?post=6196"},{"taxonomy":"all-tags","embeddable":true,"href":"https:\/\/jozotg.com\/vi\/wp-json\/wp\/v2\/all-tags?post=6196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}